{"id":11182,"date":"2023-07-18T12:09:43","date_gmt":"2023-07-18T10:09:43","guid":{"rendered":"https:\/\/hifmb.de\/people\/bernd-michael-fernengel\/"},"modified":"2025-09-17T13:57:21","modified_gmt":"2025-09-17T11:57:21","slug":"bernd-michael-fernengel","status":"publish","type":"people","link":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/","title":{"rendered":"Bernd Michael Fernengel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-theme-spacer  height-xxs\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Vita<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2023<\/strong> <strong>&#8211; heute<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PostDoc am HIFMB<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2023<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PhD (Physik , TU Darmstadt)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2018<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Master (Physik , TU Darmstadt)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2016<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bachelor (Mathematik, TU Darmstadt)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2015<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bachelor (Physik , TU Darmstadt)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-theme-spacer  height-xxs\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Forschungsschwerpunkte<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Komplexe Systeme, Statistische Physik, Netzwerktheorie<\/p>\n","protected":false},"featured_media":11180,"template":"","team":[63],"research-area":[43],"status-group":[71],"alphabet":[70],"class_list":["post-11182","people","type-people","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bernd Michael Fernengel - HIFMB Oldenburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bernd Michael Fernengel - HIFMB Oldenburg\" \/>\n<meta property=\"og:description\" content=\"Vita  2023 &#8211; heute  PostDoc am HIFMB  2023  PhD (Physik , TU Darmstadt)  2018  Master (Physik , TU Darmstadt)  2016  Bachelor (Mathematik, TU Darmstadt)  2015  Bachelor (Physik , TU Darmstadt)      Forschungsschwerpunkte  Komplexe Systeme, Statistische Physik, NetzwerktheorieWeiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/\" \/>\n<meta property=\"og:site_name\" content=\"HIFMB Oldenburg\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T11:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hifmb.de\/wp-content\/uploads\/2023\/07\/Bernd-Michael-Fernengel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"562\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/\",\"url\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/\",\"name\":\"Bernd Michael Fernengel - HIFMB Oldenburg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hifmb.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Bernd-Michael-Fernengel.jpg\",\"datePublished\":\"2023-07-18T10:09:43+00:00\",\"dateModified\":\"2025-09-17T11:57:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hifmb.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Bernd-Michael-Fernengel.jpg\",\"contentUrl\":\"https:\\\/\\\/hifmb.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Bernd-Michael-Fernengel.jpg\",\"width\":562,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/de\\\/personen\\\/bernd-michael-fernengel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hifmb.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bernd Michael Fernengel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/#website\",\"url\":\"https:\\\/\\\/hifmb.de\\\/\",\"name\":\"HIFMB Oldenburg\",\"description\":\"The Helmholtz Institute for Functional Marine Biodiversity (HIFMB)\",\"publisher\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hifmb.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/#organization\",\"name\":\"HIFMB Oldenburg\",\"url\":\"https:\\\/\\\/hifmb.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/hifmb.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hifmb.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hifmb-logo-neg-de.svg\",\"contentUrl\":\"https:\\\/\\\/hifmb.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/hifmb-logo-neg-de.svg\",\"width\":300,\"height\":87,\"caption\":\"HIFMB Oldenburg\"},\"image\":{\"@id\":\"https:\\\/\\\/hifmb.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bernd Michael Fernengel - HIFMB Oldenburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/","og_locale":"de_DE","og_type":"article","og_title":"Bernd Michael Fernengel - HIFMB Oldenburg","og_description":"Vita  2023 &#8211; heute  PostDoc am HIFMB  2023  PhD (Physik , TU Darmstadt)  2018  Master (Physik , TU Darmstadt)  2016  Bachelor (Mathematik, TU Darmstadt)  2015  Bachelor (Physik , TU Darmstadt)      Forschungsschwerpunkte  Komplexe Systeme, Statistische Physik, NetzwerktheorieWeiterlesen","og_url":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/","og_site_name":"HIFMB Oldenburg","article_modified_time":"2025-09-17T11:57:21+00:00","og_image":[{"width":562,"height":563,"url":"https:\/\/hifmb.de\/wp-content\/uploads\/2023\/07\/Bernd-Michael-Fernengel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/","url":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/","name":"Bernd Michael Fernengel - HIFMB Oldenburg","isPartOf":{"@id":"https:\/\/hifmb.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/#primaryimage"},"image":{"@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/#primaryimage"},"thumbnailUrl":"https:\/\/hifmb.de\/wp-content\/uploads\/2023\/07\/Bernd-Michael-Fernengel.jpg","datePublished":"2023-07-18T10:09:43+00:00","dateModified":"2025-09-17T11:57:21+00:00","breadcrumb":{"@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/#primaryimage","url":"https:\/\/hifmb.de\/wp-content\/uploads\/2023\/07\/Bernd-Michael-Fernengel.jpg","contentUrl":"https:\/\/hifmb.de\/wp-content\/uploads\/2023\/07\/Bernd-Michael-Fernengel.jpg","width":562,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/hifmb.de\/de\/personen\/bernd-michael-fernengel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hifmb.de\/de\/"},{"@type":"ListItem","position":2,"name":"Bernd Michael Fernengel"}]},{"@type":"WebSite","@id":"https:\/\/hifmb.de\/#website","url":"https:\/\/hifmb.de\/","name":"HIFMB Oldenburg","description":"The Helmholtz Institute for Functional Marine Biodiversity (HIFMB)","publisher":{"@id":"https:\/\/hifmb.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hifmb.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/hifmb.de\/#organization","name":"HIFMB Oldenburg","url":"https:\/\/hifmb.de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/hifmb.de\/#\/schema\/logo\/image\/","url":"https:\/\/hifmb.de\/wp-content\/uploads\/2021\/01\/hifmb-logo-neg-de.svg","contentUrl":"https:\/\/hifmb.de\/wp-content\/uploads\/2021\/01\/hifmb-logo-neg-de.svg","width":300,"height":87,"caption":"HIFMB Oldenburg"},"image":{"@id":"https:\/\/hifmb.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/people\/11182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/types\/people"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/media\/11180"}],"wp:attachment":[{"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/media?parent=11182"}],"wp:term":[{"taxonomy":"team","embeddable":true,"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/team?post=11182"},{"taxonomy":"research-area","embeddable":true,"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/research-area?post=11182"},{"taxonomy":"status-group","embeddable":true,"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/status-group?post=11182"},{"taxonomy":"alphabet","embeddable":true,"href":"https:\/\/hifmb.de\/de\/wp-json\/wp\/v2\/alphabet?post=11182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}